{"id":51366,"date":"2026-05-12T18:29:10","date_gmt":"2026-05-12T21:29:10","guid":{"rendered":"https:\/\/megaeletronicosjc.com.br\/?p=51366"},"modified":"2026-05-12T18:29:10","modified_gmt":"2026-05-12T21:29:10","slug":"novos-celulares-dobraveis-da-motorola-chegam-ao-brasil-a-partir-de-r-5-399","status":"publish","type":"post","link":"https:\/\/megaeletronicosjc.com.br\/index.php\/2026\/05\/12\/novos-celulares-dobraveis-da-motorola-chegam-ao-brasil-a-partir-de-r-5-399\/","title":{"rendered":"Novos celulares dobr\u00e1veis da Motorola chegam ao Brasil a partir de R$ 5.399"},"content":{"rendered":"<p>A Motorola oficializou hoje (12) no Brasil a sua nova linha de celulares dobr\u00e1veis, incluindo um in\u00e9dito modelo do tipo fold ? com tela grande como um tablet quando aberto ?, que chega por R$ 15.999 (R$ 11.499 \u00e0 vista com cupom). J\u00e1 os dobr\u00e1veis compactos razr 70 e razr 70 ultra partem de R$ 5.999 (R$ 5.399 \u00e0 vista) e R$ 12.999 (R$ 10.799 \u00e0 vista), respectivamente. <img src=\"https:\/\/conteudo.imguol.com.br\/c\/guia-de-compras\/17\/2026\/04\/29\/motorola-razr-fold-e-motorola-razr-70-ultra-1777487622194_v2_142x100.png\" align=\"left\">  A Motorola oficializou hoje (12) no Brasil a sua nova linha de celulares dobr\u00e1veis, incluindo um in\u00e9dito modelo do tipo fold ? com tela grande como um tablet quando aberto ?, que chega por R$ 15.999 (R$ 11.499 \u00e0 vista com cupom). J\u00e1 os dobr\u00e1veis compactos razr 70 e razr 70 ultra partem de R$ 5.999 (R$ 5.399 \u00e0 vista) e R$ 12.999 (R$ 10.799 \u00e0 vista), respectivamente.<br \/>\n<a href=\"https:\/\/www.uol.com.br\/guia-de-compras\/ultimas-noticias\/2026\/05\/12\/motorola-razr-70-e-razr-fold-chegam-ao-brasil-a-partir-de-r-5999.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Motorola oficializou hoje (12) no Brasil a sua nova linha de celulares dobr\u00e1veis, incluindo um in\u00e9dito modelo do tipo fold ? com tela grande como um tablet quando aberto ?, que chega por R$ 15.999 (R$ 11.499 \u00e0 vista com cupom). J\u00e1 os dobr\u00e1veis compactos razr 70 e razr 70 ultra partem de R$ [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[74],"tags":[],"nelio_content":{"isAutoShareEnabled":true,"followers":[],"suggestedReferences":[],"includedReferences":[],"efiUrl":"","efiAlt":""},"_links":{"self":[{"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51366"}],"collection":[{"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51366"}],"version-history":[{"count":0,"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51366\/revisions"}],"wp:attachment":[{"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megaeletronicosjc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}